{"id":11815,"date":"2020-08-20T12:56:39","date_gmt":"2021-03-03T15:52:09","guid":{"rendered":"https:\/\/padillacarretillaselevadoras.com\/producto\/wpl201\/"},"modified":"2021-03-19T10:44:33","modified_gmt":"2021-03-19T10:44:33","slug":"wpl201-2","status":"publish","type":"product","link":"https:\/\/padillacarretillaselevadoras.com\/en\/catalogo\/wpl201-2\/","title":{"rendered":"WPL201"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<ul>\n<li><b>Battery:<\/b> LITHIUM 48V\/30Ah<\/li>\n<li><b>Capacity: <\/b> 2000 Kg<\/li>\n<li><b>Fork length:<br \/>\n<\/b> Min: 800 mm<br \/>\nMax: 1220 mm<\/li>\n<li><b>Fork Width: <\/b> 560\/685mm<\/li>\n<li><strong>Travel speed:<\/strong><br \/>\n5.5 km\/h.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-1463\" src=\"https:\/\/mbforklift.com\/wp-content\/uploads\/2020\/08\/litio.png\" alt=\"\" width=\"87\" height=\"34\"><\/p>\n","protected":false},"featured_media":11816,"template":"","meta":[],"product_cat":[414,819,832,811,831],"product_tag":[500,499,502],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>WPL201 - Padilla Carretillas Elevadoras 4.0<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/padillacarretillaselevadoras.com\/en\/catalogo\/wpl201-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WPL201 - Padilla Carretillas Elevadoras 4.0\" \/>\n<meta property=\"og:description\" content=\"Battery: LITHIUM 48V\/30Ah  Capacity: 2000 Kg  Fork length:  Min: 800 mm Max: 1220 mm  Fork Width: 560\/685mm  Travel speed: 5.5 km\/h.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/padillacarretillaselevadoras.com\/en\/catalogo\/wpl201-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Padilla Carretillas Elevadoras 4.0\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-19T10:44:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/padillacarretillaselevadoras.com\/wp-content\/uploads\/2021\/02\/wpl201.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/padillacarretillaselevadoras.com\/en\/catalogo\/wpl201-2\/\",\"url\":\"https:\/\/padillacarretillaselevadoras.com\/en\/catalogo\/wpl201-2\/\",\"name\":\"WPL201 - Padilla Carretillas Elevadoras 4.0\",\"isPartOf\":{\"@id\":\"https:\/\/padillacarretillaselevadoras.com\/#website\"},\"datePublished\":\"2021-03-03T15:52:09+00:00\",\"dateModified\":\"2021-03-19T10:44:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/padillacarretillaselevadoras.com\/en\/catalogo\/wpl201-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/padillacarretillaselevadoras.com\/en\/catalogo\/wpl201-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/padillacarretillaselevadoras.com\/en\/catalogo\/wpl201-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/padillacarretillaselevadoras.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/padillacarretillaselevadoras.com\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"WPL201\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/padillacarretillaselevadoras.com\/#website\",\"url\":\"https:\/\/padillacarretillaselevadoras.com\/\",\"name\":\"Padilla Carretillas Elevadoras 4.0\",\"description\":\"Carretillas elevadoras en Tenerife\",\"publisher\":{\"@id\":\"https:\/\/padillacarretillaselevadoras.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/padillacarretillaselevadoras.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/padillacarretillaselevadoras.com\/#organization\",\"name\":\"Padilla Carretillas Elevadoras 4.0\",\"url\":\"https:\/\/padillacarretillaselevadoras.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/padillacarretillaselevadoras.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/padillacarretillaselevadoras.com\/wp-content\/uploads\/2018\/01\/logoWeb.png\",\"contentUrl\":\"https:\/\/padillacarretillaselevadoras.com\/wp-content\/uploads\/2018\/01\/logoWeb.png\",\"width\":255,\"height\":76,\"caption\":\"Padilla Carretillas Elevadoras 4.0\"},\"image\":{\"@id\":\"https:\/\/padillacarretillaselevadoras.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WPL201 - Padilla Carretillas Elevadoras 4.0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/padillacarretillaselevadoras.com\/en\/catalogo\/wpl201-2\/","og_locale":"en_US","og_type":"article","og_title":"WPL201 - Padilla Carretillas Elevadoras 4.0","og_description":"Battery: LITHIUM 48V\/30Ah  Capacity: 2000 Kg  Fork length:  Min: 800 mm Max: 1220 mm  Fork Width: 560\/685mm  Travel speed: 5.5 km\/h.","og_url":"https:\/\/padillacarretillaselevadoras.com\/en\/catalogo\/wpl201-2\/","og_site_name":"Padilla Carretillas Elevadoras 4.0","article_modified_time":"2021-03-19T10:44:33+00:00","og_image":[{"width":900,"height":900,"url":"https:\/\/padillacarretillaselevadoras.com\/wp-content\/uploads\/2021\/02\/wpl201.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/padillacarretillaselevadoras.com\/en\/catalogo\/wpl201-2\/","url":"https:\/\/padillacarretillaselevadoras.com\/en\/catalogo\/wpl201-2\/","name":"WPL201 - Padilla Carretillas Elevadoras 4.0","isPartOf":{"@id":"https:\/\/padillacarretillaselevadoras.com\/#website"},"datePublished":"2021-03-03T15:52:09+00:00","dateModified":"2021-03-19T10:44:33+00:00","breadcrumb":{"@id":"https:\/\/padillacarretillaselevadoras.com\/en\/catalogo\/wpl201-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/padillacarretillaselevadoras.com\/en\/catalogo\/wpl201-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/padillacarretillaselevadoras.com\/en\/catalogo\/wpl201-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/padillacarretillaselevadoras.com\/en\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/padillacarretillaselevadoras.com\/tienda\/"},{"@type":"ListItem","position":3,"name":"WPL201"}]},{"@type":"WebSite","@id":"https:\/\/padillacarretillaselevadoras.com\/#website","url":"https:\/\/padillacarretillaselevadoras.com\/","name":"Padilla Carretillas Elevadoras 4.0","description":"Carretillas elevadoras en Tenerife","publisher":{"@id":"https:\/\/padillacarretillaselevadoras.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/padillacarretillaselevadoras.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/padillacarretillaselevadoras.com\/#organization","name":"Padilla Carretillas Elevadoras 4.0","url":"https:\/\/padillacarretillaselevadoras.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/padillacarretillaselevadoras.com\/#\/schema\/logo\/image\/","url":"https:\/\/padillacarretillaselevadoras.com\/wp-content\/uploads\/2018\/01\/logoWeb.png","contentUrl":"https:\/\/padillacarretillaselevadoras.com\/wp-content\/uploads\/2018\/01\/logoWeb.png","width":255,"height":76,"caption":"Padilla Carretillas Elevadoras 4.0"},"image":{"@id":"https:\/\/padillacarretillaselevadoras.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/padillacarretillaselevadoras.com\/en\/wp-json\/wp\/v2\/product\/11815"}],"collection":[{"href":"https:\/\/padillacarretillaselevadoras.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/padillacarretillaselevadoras.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/padillacarretillaselevadoras.com\/en\/wp-json\/wp\/v2\/media\/11816"}],"wp:attachment":[{"href":"https:\/\/padillacarretillaselevadoras.com\/en\/wp-json\/wp\/v2\/media?parent=11815"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/padillacarretillaselevadoras.com\/en\/wp-json\/wp\/v2\/product_cat?post=11815"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/padillacarretillaselevadoras.com\/en\/wp-json\/wp\/v2\/product_tag?post=11815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}